{"id":50,"count":18,"description":"","link":"https:\/\/www.lasteuropeans.eu\/en\/category\/anti-semitism\/","name":"Anti-Semitism","slug":"anti-semitism","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.lasteuropeans.eu\/en\/wp-json\/wp\/v2\/categories\/50"}],"collection":[{"href":"https:\/\/www.lasteuropeans.eu\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.lasteuropeans.eu\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.lasteuropeans.eu\/en\/wp-json\/wp\/v2\/posts?categories=50"},{"href":"https:\/\/www.lasteuropeans.eu\/en\/wp-json\/wp\/v2\/pages?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}